{"id":1077,"count":1,"description":"","link":"https:\/\/cinema.zorarte.community\/index.php\/director\/yuji-asada\/","name":"Yuji Asada","slug":"yuji-asada","taxonomy":"dtdirector","meta":[],"_links":{"self":[{"href":"https:\/\/cinema.zorarte.community\/index.php\/wp-json\/wp\/v2\/dtdirector\/1077","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cinema.zorarte.community\/index.php\/wp-json\/wp\/v2\/dtdirector"}],"about":[{"href":"https:\/\/cinema.zorarte.community\/index.php\/wp-json\/wp\/v2\/taxonomies\/dtdirector"}],"wp:post_type":[{"href":"https:\/\/cinema.zorarte.community\/index.php\/wp-json\/wp\/v2\/movies?dtdirector=1077"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}