{"id":6553,"count":1,"description":"","link":"https:\/\/cinema.zorarte.community\/index.php\/cast\/zhu-jun-lin\/","name":"Zhu Jun Lin","slug":"zhu-jun-lin","taxonomy":"dtcast","meta":[],"_links":{"self":[{"href":"https:\/\/cinema.zorarte.community\/index.php\/wp-json\/wp\/v2\/dtcast\/6553","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cinema.zorarte.community\/index.php\/wp-json\/wp\/v2\/dtcast"}],"about":[{"href":"https:\/\/cinema.zorarte.community\/index.php\/wp-json\/wp\/v2\/taxonomies\/dtcast"}],"wp:post_type":[{"href":"https:\/\/cinema.zorarte.community\/index.php\/wp-json\/wp\/v2\/tvshows?dtcast=6553"},{"href":"https:\/\/cinema.zorarte.community\/index.php\/wp-json\/wp\/v2\/movies?dtcast=6553"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}