{"id":5396,"count":1,"description":"","link":"https:\/\/cinema.zorarte.community\/index.php\/cast\/harsh-usdadiya\/","name":"Harsh Usdadiya","slug":"harsh-usdadiya","taxonomy":"dtcast","meta":[],"_links":{"self":[{"href":"https:\/\/cinema.zorarte.community\/index.php\/wp-json\/wp\/v2\/dtcast\/5396","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cinema.zorarte.community\/index.php\/wp-json\/wp\/v2\/dtcast"}],"about":[{"href":"https:\/\/cinema.zorarte.community\/index.php\/wp-json\/wp\/v2\/taxonomies\/dtcast"}],"wp:post_type":[{"href":"https:\/\/cinema.zorarte.community\/index.php\/wp-json\/wp\/v2\/tvshows?dtcast=5396"},{"href":"https:\/\/cinema.zorarte.community\/index.php\/wp-json\/wp\/v2\/movies?dtcast=5396"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}