{"id":5140,"count":1,"description":"","link":"https:\/\/cinema.zorarte.community\/index.php\/cast\/naz-cagla-irmak\/","name":"Naz \u00c7a\u011fla Irmak","slug":"naz-cagla-irmak","taxonomy":"dtcast","meta":[],"_links":{"self":[{"href":"https:\/\/cinema.zorarte.community\/index.php\/wp-json\/wp\/v2\/dtcast\/5140","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cinema.zorarte.community\/index.php\/wp-json\/wp\/v2\/dtcast"}],"about":[{"href":"https:\/\/cinema.zorarte.community\/index.php\/wp-json\/wp\/v2\/taxonomies\/dtcast"}],"wp:post_type":[{"href":"https:\/\/cinema.zorarte.community\/index.php\/wp-json\/wp\/v2\/tvshows?dtcast=5140"},{"href":"https:\/\/cinema.zorarte.community\/index.php\/wp-json\/wp\/v2\/movies?dtcast=5140"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}