{"id":146,"count":2,"description":"","link":"https:\/\/cinema.zorarte.community\/index.php\/cast\/loreto-valenzuela\/","name":"Loreto Valenzuela","slug":"loreto-valenzuela","taxonomy":"dtcast","meta":[],"_links":{"self":[{"href":"https:\/\/cinema.zorarte.community\/index.php\/wp-json\/wp\/v2\/dtcast\/146","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cinema.zorarte.community\/index.php\/wp-json\/wp\/v2\/dtcast"}],"about":[{"href":"https:\/\/cinema.zorarte.community\/index.php\/wp-json\/wp\/v2\/taxonomies\/dtcast"}],"wp:post_type":[{"href":"https:\/\/cinema.zorarte.community\/index.php\/wp-json\/wp\/v2\/tvshows?dtcast=146"},{"href":"https:\/\/cinema.zorarte.community\/index.php\/wp-json\/wp\/v2\/movies?dtcast=146"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}